{"id":4492,"date":"2026-05-12T19:49:15","date_gmt":"2026-05-12T17:49:15","guid":{"rendered":"https:\/\/sicilia.agesci.it\/csd\/?p=4492"},"modified":"2026-05-12T17:29:29","modified_gmt":"2026-05-12T15:29:29","slug":"il-segreto-dei-tetti-morti-di-francesco-tripodi","status":"publish","type":"post","link":"https:\/\/sicilia.agesci.it\/csd\/il-segreto-dei-tetti-morti-di-francesco-tripodi\/","title":{"rendered":"&#8220;Il segreto dei tetti morti&#8221; di Francesco Tripodi"},"content":{"rendered":"<p>Il romanzo Il segreto dei tetti morti di Francesco Tripodi, del 1997 \u00e8 un racconto per ragazzi che intreccia elementi di avventura e mistero con uno sfondo storico legato allo scautismo italiano durante il periodo fascista. Il libro si colloca nel filone della narrativa educativa che utilizza la forma del racconto avventuroso per trasmettere valori di amicizia, lealt\u00e0 e coraggio.<\/p>\n<p>La vicenda si sviluppa attorno a un gruppo di giovani di Sciacca che, tra esplorazioni urbane e piccole indagini, scoprono un mistero legato ai \u201ctetti morti\u201d, spazi dimenticati della citt\u00e0 che diventano simbolicamente luoghi di libert\u00e0 e di immaginazione. Attraverso questo espediente narrativo il romanzo restituisce l\u2019atmosfera emotiva dei ragazzi che vivevano lo scautismo come un\u2019esperienza di crescita e di fraternit\u00e0.<\/p>\n<p>Il contesto storico evocato dal libro rimanda agli anni in cui il regime fascista impose la chiusura delle associazioni scout. Tra il 1927 e il 1928 il governo di Benito Mussolini decret\u00f2 infatti lo scioglimento delle organizzazioni scout, con l\u2019obiettivo di concentrare l\u2019educazione giovanile nelle strutture ufficiali del regime, in particolare l\u2019Opera Nazionale Balilla. Questa decisione interruppe bruscamente un\u2019esperienza educativa che aveva coinvolto migliaia di ragazzi, costringendo molti riparti a sciogliersi.<\/p>\n<p>Nel libro emerge soprattutto la dimensione umana ed emotiva di quella frattura: per molti giovani lo scautismo non era solo un gioco, ma un luogo di amicizia, responsabilit\u00e0 e scoperta della natura. La sua soppressione gener\u00f2 smarrimento, nostalgia e anche una forma di resistenza silenziosa, come dimostrano alcune esperienze clandestine di quegli anni, tra cui quella quella pi\u00f9 conosciuta delle cosiddette \u201cAquile Randagie\u201d, che continuarono a vivere lo spirito scout nonostante i divieti.&nbsp;<\/p>\n<div style=\"clear:both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Il romanzo Il segreto dei tetti morti di Francesco Tripodi, del 1997 \u00e8 un racconto per ragazzi che intreccia elementi di avventura e mistero con uno sfondo storico legato allo [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":4493,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[722,104],"tags":[217,717,716,456,697,713],"class_list":["post-4492","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biblioteca","category-recensioni","tag-biblioteca","tag-iosonoguida","tag-iosonoscout","tag-libri","tag-scautismo","tag-scoutismo"],"jetpack_featured_media_url":"https:\/\/sicilia.agesci.it\/csd\/wp-content\/uploads\/sites\/6\/2026\/05\/Tetti-morti.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/sicilia.agesci.it\/csd\/wp-json\/wp\/v2\/posts\/4492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sicilia.agesci.it\/csd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sicilia.agesci.it\/csd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sicilia.agesci.it\/csd\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/sicilia.agesci.it\/csd\/wp-json\/wp\/v2\/comments?post=4492"}],"version-history":[{"count":1,"href":"https:\/\/sicilia.agesci.it\/csd\/wp-json\/wp\/v2\/posts\/4492\/revisions"}],"predecessor-version":[{"id":4494,"href":"https:\/\/sicilia.agesci.it\/csd\/wp-json\/wp\/v2\/posts\/4492\/revisions\/4494"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sicilia.agesci.it\/csd\/wp-json\/wp\/v2\/media\/4493"}],"wp:attachment":[{"href":"https:\/\/sicilia.agesci.it\/csd\/wp-json\/wp\/v2\/media?parent=4492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sicilia.agesci.it\/csd\/wp-json\/wp\/v2\/categories?post=4492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sicilia.agesci.it\/csd\/wp-json\/wp\/v2\/tags?post=4492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}